{"id":16809,"date":"2026-03-19T16:49:02","date_gmt":"2026-03-19T15:49:02","guid":{"rendered":"https:\/\/goldenclassicstore.com\/product\/ladekast-landelijke-stijl\/"},"modified":"2026-03-19T16:49:02","modified_gmt":"2026-03-19T15:49:02","slug":"ladekast-landelijke-stijl","status":"publish","type":"product","link":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/","title":{"rendered":"Ladekast landelijke stijl"},"content":{"rendered":"<p>Prachtige ladekast landelijke stijl van massief hout. Nieuw. <\/p>\n<p>Hoogte 90 cm<\/p>\n<p>Breedte 180 cm<\/p>\n<p>Diepte 44 cm<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ladekast van massief hout landelijke stijl<\/p>\n","protected":false},"featured_media":16810,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[52,53,85],"product_tag":[411,55],"class_list":["post-16809","product","type-product","status-publish","has-post-thumbnail","product_cat-schrank","product_cat-commodes","product_cat-nieuwe-meubelen","product_tag-dressoir","product_tag-kommode","first","instock","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ladekast landelijke stijl - Golden Classics<\/title>\n<meta name=\"description\" content=\"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ladekast landelijke stijl - Golden Classics\" \/>\n<meta property=\"og:description\" content=\"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/\" \/>\n<meta property=\"og:site_name\" content=\"Golden Classics\" \/>\n<meta property=\"og:image\" content=\"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2026\/03\/P1290900.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/\",\"url\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/\",\"name\":\"Ladekast landelijke stijl - Golden Classics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/goldenclassicstore.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1290900.jpg\",\"datePublished\":\"2026-03-19T15:49:02+00:00\",\"description\":\"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/goldenclassicstore.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1290900.jpg\",\"contentUrl\":\"https:\\\/\\\/goldenclassicstore.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/P1290900.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/product\\\/ladekast-landelijke-stijl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ladekast landelijke stijl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/\",\"name\":\"Golden Classics\",\"description\":\"Antike M\u00f6bel. Zeitlose Klasse.\",\"publisher\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#organization\",\"name\":\"Golden Classics\",\"url\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/goldenclassicstore.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo_GoldenClassics_512px_72ppi.webp\",\"contentUrl\":\"https:\\\/\\\/goldenclassicstore.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo_GoldenClassics_512px_72ppi.webp\",\"width\":512,\"height\":200,\"caption\":\"Golden Classics\"},\"image\":{\"@id\":\"https:\\\/\\\/goldenclassicstore.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ladekast landelijke stijl - Golden Classics","description":"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/","og_locale":"nl_NL","og_type":"article","og_title":"Ladekast landelijke stijl - Golden Classics","og_description":"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).","og_url":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/","og_site_name":"Golden Classics","og_image":[{"width":750,"height":500,"url":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2026\/03\/P1290900.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/","url":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/","name":"Ladekast landelijke stijl - Golden Classics","isPartOf":{"@id":"https:\/\/goldenclassicstore.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/#primaryimage"},"image":{"@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/#primaryimage"},"thumbnailUrl":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2026\/03\/P1290900.jpg","datePublished":"2026-03-19T15:49:02+00:00","description":"Ladekast landelijke stijl. Dressoir sideboard van massief hout. Nieuw. Wij leveren gratis door heel Duitsland. (Eilanden uitgezonderd).","breadcrumb":{"@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/#primaryimage","url":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2026\/03\/P1290900.jpg","contentUrl":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2026\/03\/P1290900.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/goldenclassicstore.com\/nl\/product\/ladekast-landelijke-stijl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/goldenclassicstore.com\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/goldenclassicstore.com\/nl\/winkel\/"},{"@type":"ListItem","position":3,"name":"Ladekast landelijke stijl"}]},{"@type":"WebSite","@id":"https:\/\/goldenclassicstore.com\/nl\/#website","url":"https:\/\/goldenclassicstore.com\/nl\/","name":"Golden Classics","description":"Antike M\u00f6bel. Zeitlose Klasse.","publisher":{"@id":"https:\/\/goldenclassicstore.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/goldenclassicstore.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/goldenclassicstore.com\/nl\/#organization","name":"Golden Classics","url":"https:\/\/goldenclassicstore.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/goldenclassicstore.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2024\/11\/Logo_GoldenClassics_512px_72ppi.webp","contentUrl":"https:\/\/goldenclassicstore.com\/wp-content\/uploads\/2024\/11\/Logo_GoldenClassics_512px_72ppi.webp","width":512,"height":200,"caption":"Golden Classics"},"image":{"@id":"https:\/\/goldenclassicstore.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/product\/16809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/comments?post=16809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/media\/16810"}],"wp:attachment":[{"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/media?parent=16809"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/product_brand?post=16809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/product_cat?post=16809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/goldenclassicstore.com\/nl\/wp-json\/wp\/v2\/product_tag?post=16809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}